{"id":83162,"date":"2026-07-09T11:13:21","date_gmt":"2026-07-09T17:13:21","guid":{"rendered":"https:\/\/centroprodh.org.mx\/sididh4_0\/?p=83162"},"modified":"2026-07-09T11:13:21","modified_gmt":"2026-07-09T17:13:21","slug":"leopoldo-maldonado-es-designado-como-relator-especial-para-la-promocion-y-proteccion-del-derecho-a-la-libertad-de-expresion-y-opinion-de-la-onu","status":"publish","type":"post","link":"https:\/\/centroprodh.org.mx\/sididh4_0\/2026\/07\/09\/leopoldo-maldonado-es-designado-como-relator-especial-para-la-promocion-y-proteccion-del-derecho-a-la-libertad-de-expresion-y-opinion-de-la-onu\/","title":{"rendered":"Leopoldo Maldonado es designado como Relator Especial para la Promoci\u00f3n y Protecci\u00f3n del Derecho a la Libertad de Expresi\u00f3n y Opini\u00f3n de la ONU"},"content":{"rendered":"<body><p><\/p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-83163\" src=\"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-content\/uploads\/2026\/07\/imagen_2026-07-09_025157396.png\" alt=\"\" width=\"350\" height=\"350\" loading=\"lazy\" srcset=\"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-content\/uploads\/2026\/07\/imagen_2026-07-09_025157396.png 1080w, https:\/\/centroprodh.org.mx\/sididh4_0\/wp-content\/uploads\/2026\/07\/imagen_2026-07-09_025157396-300x300.png 300w, https:\/\/centroprodh.org.mx\/sididh4_0\/wp-content\/uploads\/2026\/07\/imagen_2026-07-09_025157396-1024x1024.png 1024w, https:\/\/centroprodh.org.mx\/sididh4_0\/wp-content\/uploads\/2026\/07\/imagen_2026-07-09_025157396-150x150.png 150w, https:\/\/centroprodh.org.mx\/sididh4_0\/wp-content\/uploads\/2026\/07\/imagen_2026-07-09_025157396-768x768.png 768w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>\n<p class=\"font-claude-response-body break-words whitespace-normal\"><span style=\"text-decoration: underline;\"><strong>Leopoldo Maldonado Guti\u00e9rrez<\/strong><\/span>, director regional de <strong><em>ARTICLE 19 M\u00e9xico y Centroam\u00e9rica<\/em><\/strong>, fue <strong>designado<\/strong> por el <em><strong>Consejo de Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas<\/strong><\/em> como <span style=\"text-decoration: underline;\"><strong>Relator Especial para la Promoci\u00f3n y Protecci\u00f3n del Derecho a la Libertad de Expresi\u00f3n y Opini\u00f3n<\/strong><\/span>.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">La Relator\u00eda Especial es uno de los <strong>mecanismos independientes<\/strong> <strong>m\u00e1s relevantes del sistema universal<\/strong> para <strong>defender<\/strong> este derecho a <strong>escala global<\/strong>, y el nombramiento de Maldonado <strong>reconoce casi dos d\u00e9cadas de trabajo sostenido junto a periodistas<\/strong>, <strong>comunidades<\/strong> y <strong>organizaciones de la sociedad civil<\/strong> en la regi\u00f3n.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\"><a href=\"https:\/\/x.com\/CentroProdh\/status\/2074873245556166983\">Desde el <strong><em>Centro Prodh<\/em><\/strong><\/a> <strong>celebramos este nombramiento <\/strong>y <strong>reconocemos<\/strong> que su <strong>experiencia en la defensa de la libertad de expresi\u00f3n<\/strong> y su <strong>cercan\u00eda con las v\u00edctimas<\/strong> son lo que m\u00e1s <strong>necesitan<\/strong> hoy los <span style=\"text-decoration: underline;\"><strong>Procedimientos Especiales de la ONU<\/strong><\/span>, en un momento en que el <strong>sistema multilateral de derechos humanos enfrenta presiones crecientes<\/strong>.<\/p>\n<p>Lee el <a href=\"https:\/\/articulo19.org\/leopoldo-maldonado-es-designado-como-relator-especial-para-la-promocion-y-proteccion-del-derecho-a-la-libertad-de-expresion-y-opinion-de-la-onu\/\">comunicado de <strong><em>Article 19<\/em><\/strong><\/a>.<\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>Leopoldo Maldonado Guti\u00e9rrez, director regional de ARTICLE 19 M\u00e9xico y Centroam\u00e9rica, fue designado por el Consejo de Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas como Relator Especial para la Promoci\u00f3n y Protecci\u00f3n del Derecho a la Libertad de Expresi\u00f3n y Opini\u00f3n. La Relator\u00eda Especial es uno de los mecanismos independientes m\u00e1s relevantes del [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[969,640,46,1583],"class_list":["post-83162","post","type-post","status-publish","format-standard","hentry","category-paso-en-la-semana","tag-leopoldo-maldonado","tag-libertad-de-expresion","tag-onu","tag-relator-especial"],"_links":{"self":[{"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/posts\/83162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/comments?post=83162"}],"version-history":[{"count":1,"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/posts\/83162\/revisions"}],"predecessor-version":[{"id":83164,"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/posts\/83162\/revisions\/83164"}],"wp:attachment":[{"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/media?parent=83162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/categories?post=83162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centroprodh.org.mx\/sididh4_0\/wp-json\/wp\/v2\/tags?post=83162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}